{"id":47974,"date":"2024-04-18T09:19:47","date_gmt":"2024-04-18T09:19:47","guid":{"rendered":"https:\/\/silmantech.com\/?p=47974"},"modified":"2024-04-18T09:19:49","modified_gmt":"2024-04-18T09:19:49","slug":"methods-of-bga-reballing","status":"publish","type":"post","link":"https:\/\/silmantech.com\/fr\/methods-of-bga-reballing\/","title":{"rendered":"M\u00e9thodes de rebasage des BGA"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Il existe diff\u00e9rentes m\u00e9thodes pour placer les billes des puces BGA (Ball Grid Array). Aujourd'hui, Silman Tech explique qu'elles peuvent \u00eatre class\u00e9es en diff\u00e9rentes cat\u00e9gories :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>En fonction de l'op\u00e9rateur, le placement de billes BGA peut \u00eatre divis\u00e9 en deux cat\u00e9gories : le placement de billes \u00e0 la machine et le placement de billes \u00e0 la main.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Le placement de billes \u00e0 la machine implique la mise en place d'un programme, puis la machine effectue de mani\u00e8re autonome le placement des billes BGA. Les avantages du placement de billes \u00e0 la machine comprennent un rendement \u00e9lev\u00e9 de la retouche, des \u00e9conomies sur les co\u00fbts de main-d'\u0153uvre et une grande efficacit\u00e9 de la retouche. Cependant, l'inconv\u00e9nient est le prix \u00e9lev\u00e9. Actuellement, des machines automatiques de placement de billes comme la machine de placement de billes BGA de Silman Tech sont disponibles sur le march\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mise en place manuelle des billes repose sur l'utilisation de machines simples par les ouvriers pour effectuer la mise en place des billes BGA. L'avantage de cette m\u00e9thode est le co\u00fbt relativement faible des BGA, mais ses inconv\u00e9nients sont une faible efficacit\u00e9 de reprise, un faible rendement de reprise et des co\u00fbts de main-d'\u0153uvre \u00e9lev\u00e9s.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\">\n<li>En fonction des mat\u00e9riaux utilis\u00e9s, le placement des billes peut \u00eatre divis\u00e9 en deux m\u00e9thodes : p\u00e2te \u00e0 braser + bille de soudure et flux + bille de soudure. Il existe aujourd'hui deux m\u00e9thodes populaires de placement de la bille dans l'industrie : p\u00e2te \u00e0 souder + bille de soudure et flux + bille de soudure.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">La p\u00e2te \u00e0 braser + bille de soudure est consid\u00e9r\u00e9e comme la meilleure et la plus standard des m\u00e9thodes de placement des billes. Cette m\u00e9thode produit des billes de soudure avec une bonne soudabilit\u00e9, une bonne brillance et minimise le risque de migration des billes de soudure pendant la soudure. Le processus sp\u00e9cifique consiste \u00e0 imprimer de la p\u00e2te \u00e0 braser sur les pads BGA, puis \u00e0 placer des billes de soudure dessus. La p\u00e2te \u00e0 braser agit comme un adh\u00e9sif pour maintenir les billes de soudure en place et augmente la surface de contact entre les billes de soudure et les plaques BGA, ce qui am\u00e9liore la qualit\u00e9 des joints de soudure et r\u00e9duit le risque d'apparition de vides.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le flux + boule de soudure consiste \u00e0 utiliser du flux \u00e0 la place de la p\u00e2te \u00e0 braser. Cependant, le flux se comporte diff\u00e9remment de la p\u00e2te \u00e0 braser ; il devient liquide \u00e0 des temp\u00e9ratures \u00e9lev\u00e9es, ce qui rend les billes de soudure susceptibles de migrer. En outre, les propri\u00e9t\u00e9s de brasage du flux sont inf\u00e9rieures \u00e0 celles de la p\u00e2te \u00e0 braser. Par cons\u00e9quent, la premi\u00e8re m\u00e9thode (p\u00e2te \u00e0 braser + bille de soudure) est plus id\u00e9ale pour le placement des billes.<\/p>","protected":false},"excerpt":{"rendered":"<p>Il existe diff\u00e9rentes m\u00e9thodes pour placer les billes des puces BGA (Ball Grid Array). Aujourd'hui, Silman Tech explique qu'elles peuvent \u00eatre class\u00e9es en diff\u00e9rentes cat\u00e9gories : Le placement de billes \u00e0 la machine implique la mise en place d'un programme, puis la machine effectue de mani\u00e8re autonome le placement des billes BGA. Les avantages du placement de billes \u00e0 la machine comprennent un rendement \u00e9lev\u00e9 de...<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","footnotes":""},"categories":[86,1],"tags":[],"class_list":["post-47974","post","type-post","status-publish","format-standard","hentry","category-bga-rework-station","category-news","category-86","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/silmantech.com\/fr\/wp-json\/wp\/v2\/posts\/47974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silmantech.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/silmantech.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/silmantech.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/silmantech.com\/fr\/wp-json\/wp\/v2\/comments?post=47974"}],"version-history":[{"count":0,"href":"https:\/\/silmantech.com\/fr\/wp-json\/wp\/v2\/posts\/47974\/revisions"}],"wp:attachment":[{"href":"https:\/\/silmantech.com\/fr\/wp-json\/wp\/v2\/media?parent=47974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/silmantech.com\/fr\/wp-json\/wp\/v2\/categories?post=47974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/silmantech.com\/fr\/wp-json\/wp\/v2\/tags?post=47974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}